{"id":3642,"date":"2025-12-08T16:46:07","date_gmt":"2025-12-08T22:46:07","guid":{"rendered":"https:\/\/lgbs.dev2live.com\/?post_type=attorney&#038;p=3642"},"modified":"2025-12-16T11:57:53","modified_gmt":"2025-12-16T17:57:53","slug":"marissa-wakhu","status":"publish","type":"attorney","link":"https:\/\/www.lgbs.com\/es\/attorney\/marissa-wakhu\/","title":{"rendered":"Marissa Wakhu"},"content":{"rendered":"\n<p>Marissa Wakhu se incorpor\u00f3 a Linebarger en 2025 como abogada del \u00e1rea de quiebras de la oficina de Houston. Wakhu aporta una amplia experiencia jur\u00eddica y una gran pasi\u00f3n por servir a los clientes del bufete.<\/p>\n\n\n\n<p>Antes de estudiar derecho, Wakhu obtuvo su licenciatura en Ciencias Pol\u00edticas en la Universidad de Baylor. Tambi\u00e9n adquiri\u00f3 una importante experiencia jur\u00eddica como asistente legal en un bufete de abogados boutique de Houston, donde trabaj\u00f3 en complejos asuntos sucesorios. Anteriormente, Wakhu trabaj\u00f3 como pasante jur\u00eddica en Waco, donde prest\u00f3 apoyo a abogados en materia de derecho de familia, penal y de inmigraci\u00f3n.<\/p>\n\n\n\n<p>Wakhu tiene un doctorado en Derecho por la Facultad de Derecho Thurgood Marshall de la Universidad del Sur de Texas, donde se distingui\u00f3 como una de las mejores abogadas en numerosas competiciones de tribunales simulados, entre ellas la Concurso de Tribunales Simulados de Quiebras Duberstein, la 5.\u00aa Copa Elliott de Tribunales Simulados de Quiebras y el Concurso de Tribunales Simulados Henry-Doyle. Reconocida por sus excepcionales habilidades argumentativas, Wakhu ha recibido premios a la mejor oradora en la 33\u00aa edici\u00f3n de la Duberstein Moot Court Competition y a la mejor abogada en los programas de abogac\u00eda como estudiante de derecho de segundo y tercer a\u00f1o. Wakhu tambi\u00e9n ha sido admitida en la prestigiosa sociedad de de honores para abogados, Order of Barristers.<\/p>\n\n\n\n<p>Wakhu es miembro activo del Asociaci\u00f3n de Abogados de Houston y miembro orgulloso de la hermandad Delta Sigma Theta Sorority, Incorporated.<\/p>\n","protected":false},"featured_media":3545,"menu_order":0,"template":"","meta":{"_acf_changed":true},"attorney-expertise":[59],"attorney-title":[67],"class_list":["post-3642","attorney","type-attorney","status-publish","has-post-thumbnail","hentry","attorney-expertise-bancarrota","attorney-title-abogado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marissa Wakhu | Linebarger Goggan Blair &amp; Sampson, LLP<\/title>\n<meta name=\"description\" content=\"Marissa Wakhu se incorpor\u00f3 a Linebarger en 2025 como abogada del \u00e1rea de quiebras de la oficina de Houston.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lgbs.com\/es\/attorney\/marissa-wakhu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marissa Wakhu | Linebarger Goggan Blair &amp; Sampson, LLP\" \/>\n<meta property=\"og:description\" content=\"Marissa Wakhu se incorpor\u00f3 a Linebarger en 2025 como abogada del \u00e1rea de quiebras de la oficina de Houston.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lgbs.com\/es\/attorney\/marissa-wakhu\/\" \/>\n<meta property=\"og:site_name\" content=\"Linebarger Goggan Blair &amp; Sampson, LLP\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-16T17:57:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lgbs.com\/wp-content\/uploads\/2025\/12\/Wakhu-Marissa-12.25.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"1050\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/attorney\\\/marissa-wakhu\\\/\",\"url\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/attorney\\\/marissa-wakhu\\\/\",\"name\":\"Marissa Wakhu | Linebarger Goggan Blair &amp; Sampson, LLP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/attorney\\\/marissa-wakhu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/attorney\\\/marissa-wakhu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lgbs.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Wakhu-Marissa-12.25.webp\",\"datePublished\":\"2025-12-08T22:46:07+00:00\",\"dateModified\":\"2025-12-16T17:57:53+00:00\",\"description\":\"Marissa Wakhu se incorpor\u00f3 a Linebarger en 2025 como abogada del \u00e1rea de quiebras de la oficina de Houston.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/attorney\\\/marissa-wakhu\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lgbs.com\\\/es\\\/attorney\\\/marissa-wakhu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/attorney\\\/marissa-wakhu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lgbs.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Wakhu-Marissa-12.25.webp\",\"contentUrl\":\"https:\\\/\\\/www.lgbs.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Wakhu-Marissa-12.25.webp\",\"width\":750,\"height\":1050},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/attorney\\\/marissa-wakhu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marissa Wakhu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/\",\"name\":\"Linebarger\",\"description\":\"National Leader in Collections Law\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/#organization\"},\"alternateName\":\"LGBS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/#organization\",\"name\":\"Linebarger Goggan Blair & Sampson, LLP\",\"alternateName\":\"LGBS\",\"url\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lgbs.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/L-for-avatar.webp\",\"contentUrl\":\"https:\\\/\\\/www.lgbs.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/L-for-avatar.webp\",\"width\":453,\"height\":447,\"caption\":\"Linebarger Goggan Blair & Sampson, LLP\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lgbs.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/linebargerlaw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marissa Wakhu | Linebarger Goggan Blair &amp; Sampson, LLP","description":"Marissa Wakhu se incorpor\u00f3 a Linebarger en 2025 como abogada del \u00e1rea de quiebras de la oficina de Houston.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lgbs.com\/es\/attorney\/marissa-wakhu\/","og_locale":"es_ES","og_type":"article","og_title":"Marissa Wakhu | Linebarger Goggan Blair &amp; Sampson, LLP","og_description":"Marissa Wakhu se incorpor\u00f3 a Linebarger en 2025 como abogada del \u00e1rea de quiebras de la oficina de Houston.","og_url":"https:\/\/www.lgbs.com\/es\/attorney\/marissa-wakhu\/","og_site_name":"Linebarger Goggan Blair &amp; Sampson, LLP","article_modified_time":"2025-12-16T17:57:53+00:00","og_image":[{"width":750,"height":1050,"url":"https:\/\/www.lgbs.com\/wp-content\/uploads\/2025\/12\/Wakhu-Marissa-12.25.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lgbs.com\/es\/attorney\/marissa-wakhu\/","url":"https:\/\/www.lgbs.com\/es\/attorney\/marissa-wakhu\/","name":"Marissa Wakhu | Linebarger Goggan Blair &amp; Sampson, LLP","isPartOf":{"@id":"https:\/\/www.lgbs.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lgbs.com\/es\/attorney\/marissa-wakhu\/#primaryimage"},"image":{"@id":"https:\/\/www.lgbs.com\/es\/attorney\/marissa-wakhu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lgbs.com\/wp-content\/uploads\/2025\/12\/Wakhu-Marissa-12.25.webp","datePublished":"2025-12-08T22:46:07+00:00","dateModified":"2025-12-16T17:57:53+00:00","description":"Marissa Wakhu se incorpor\u00f3 a Linebarger en 2025 como abogada del \u00e1rea de quiebras de la oficina de Houston.","breadcrumb":{"@id":"https:\/\/www.lgbs.com\/es\/attorney\/marissa-wakhu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lgbs.com\/es\/attorney\/marissa-wakhu\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lgbs.com\/es\/attorney\/marissa-wakhu\/#primaryimage","url":"https:\/\/www.lgbs.com\/wp-content\/uploads\/2025\/12\/Wakhu-Marissa-12.25.webp","contentUrl":"https:\/\/www.lgbs.com\/wp-content\/uploads\/2025\/12\/Wakhu-Marissa-12.25.webp","width":750,"height":1050},{"@type":"BreadcrumbList","@id":"https:\/\/www.lgbs.com\/es\/attorney\/marissa-wakhu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lgbs.com\/es\/"},{"@type":"ListItem","position":2,"name":"Marissa Wakhu"}]},{"@type":"WebSite","@id":"https:\/\/www.lgbs.com\/es\/#website","url":"https:\/\/www.lgbs.com\/es\/","name":"Linebarger","description":"National Leader in Collections Law","publisher":{"@id":"https:\/\/www.lgbs.com\/es\/#organization"},"alternateName":"LGBS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lgbs.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.lgbs.com\/es\/#organization","name":"Linebarger Goggan Blair & Sampson, LLP","alternateName":"LGBS","url":"https:\/\/www.lgbs.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lgbs.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.lgbs.com\/wp-content\/uploads\/2025\/01\/L-for-avatar.webp","contentUrl":"https:\/\/www.lgbs.com\/wp-content\/uploads\/2025\/01\/L-for-avatar.webp","width":453,"height":447,"caption":"Linebarger Goggan Blair & Sampson, LLP"},"image":{"@id":"https:\/\/www.lgbs.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/linebargerlaw"]}]}},"_links":{"self":[{"href":"https:\/\/www.lgbs.com\/es\/wp-json\/wp\/v2\/attorney\/3642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lgbs.com\/es\/wp-json\/wp\/v2\/attorney"}],"about":[{"href":"https:\/\/www.lgbs.com\/es\/wp-json\/wp\/v2\/types\/attorney"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lgbs.com\/es\/wp-json\/wp\/v2\/media\/3545"}],"wp:attachment":[{"href":"https:\/\/www.lgbs.com\/es\/wp-json\/wp\/v2\/media?parent=3642"}],"wp:term":[{"taxonomy":"attorney-expertise","embeddable":true,"href":"https:\/\/www.lgbs.com\/es\/wp-json\/wp\/v2\/attorney-expertise?post=3642"},{"taxonomy":"attorney-title","embeddable":true,"href":"https:\/\/www.lgbs.com\/es\/wp-json\/wp\/v2\/attorney-title?post=3642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}